{"id":6773,"date":"2018-09-12T21:28:00","date_gmt":"2018-09-12T19:28:00","guid":{"rendered":"https:\/\/rehwald-associates.co.uk\/?p=6773"},"modified":"2024-08-29T21:31:59","modified_gmt":"2024-08-29T19:31:59","slug":"der-perfekte-lebenslauf-im-asset-management","status":"publish","type":"post","link":"https:\/\/rehwald-associates.co.uk\/de\/der-perfekte-lebenslauf-im-asset-management\/","title":{"rendered":"Der perfekte Lebenslauf im Asset Management"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das Asset Management geh\u00f6rt zu den wenigen Sektoren der Finanzdienstleistungen, die mit offenen Stellen gesegnet sind. \u201eEs bewegt sich momentan recht viel\u201c, beobachtet Personalberater Manuel Rehwald von Rehwald Associates in K\u00f6nigstein. Niedrige Zinsen und die lange Aktienhausse h\u00e4tten das Gesch\u00e4ft befl\u00fcgelt. \u201eNoch nie wurde so viel Geld in Deutschland verwaltet wie heute\u201c, kommentiert er. F\u00fcr die Zukunft ist Rehwald ebenfalls optimistisch. Der Brexit k\u00f6nne vor allem kleinere Fondsgesellschaften dazu zwingen, Vertriebsniederlassungen in der verbleibenden EU zu gr\u00fcnden, um hier Vertriebszulassungen zu erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ganz \u00e4hnlich sieht dies Headhunter Rolf Behrens von Banking Consult in Bad Nauheim. \u201eVor allem in den Bereichen Total Return, alternativen Investments wie Infrastrukturfonds, Real Estate oder Private Equity wird gesucht\u201c, berichtet der Berater. \u201eAuch die gro\u00dfen Versicherer bauen ihre weiter Teams aus.\u201c Institutionelle Anleger suchten angesichts der niedrigen Zinsen h\u00e4nderingend nach Alternativen zu Anleihen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch wie sieht der perfekte Lebenslauf von Portfoliomanagern und Asset Management-Sales konkret aus?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der perfekte Lebenslauf\u2026<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>1. \u2026 ist nicht zu kurz und nicht zu lang<\/mark><br>\u201eOft fallen die Angaben zu den einzelnen Stationen in den Lebensl\u00e4ufen zu kurz aus und manche Kandidaten versuchen alles, wie in den USA \u00fcblich, auf nur eine Seite unterzubringen. Das ist der h\u00e4ufigste Fehler bei Asset Management-Lebensl\u00e4ufen\u201c, klagt Rehwald. Der Personalberater empfiehlt Lebensl\u00e4ufe von zwei bis drei Seiten L\u00e4nge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dagegen mahnt die Personalabteilung von Union Investment zu K\u00fcrze: \u201eDie Lebensl\u00e4ufe sollten \u00fcbersichtlich gestaltet sein und die Stationen chronologisch geordnet sein (Aktuellstes zuerst). Auch sollte der Lebenslauf in der Regel maximal zwei Seiten umfassen.\u201c Eine un\u00fcbersichtliche Darstellung, zu kleine Schriftarten und zu wenig Zeilenabstand machten einen Lebenslauf \u201eunattraktiv\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>2. \u2026 enth\u00e4lt Erfolge statt blo\u00dfe T\u00e4tigkeitsbeschreibungen<\/mark><br>\u201eViel zu viele Lebensl\u00e4ufe beschr\u00e4nken sich bei den beruflichen Stationen auf T\u00e4tigkeitsbeschreibungen, das ist nicht genug\u201c, warnt Rehwald. \u201eIch empfehle sich auf die Erfolge zu konzentrieren.\u201c Die Beschreibungen der einzelnen Stationen d\u00fcrften daher auch nicht zu knapp ausfallen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>3. \u2026. listet Performance bzw. Track Record detailliert auf<\/mark><br>Erfolgreiche Portfoliomanager werden (selbstverst\u00e4ndlich) an der Performance der von ihnen verantworteten Fonds gemessen. Eine detaillierte Auflistung ist also Pflicht. \u201eWir bevorzugen die \u00fcbersichtliche Darstellung auf einer zus\u00e4tzlichen Seite. Hierbei sind auch Ausz\u00fcge von Datenbanken wie Bloomberg oder aus internen Performance-Messungs-Tools hilfreich\u201c, hei\u00dft es von Union Investment.<br>Rehwald r\u00e4t selbst bei Publikumsfonds Angaben zur Performance in den Lebenslauf oder den Anh\u00e4ngen aufzunehmen, obgleich diese \u00f6ffentlich sind und sich von jedermann abrufen lassen. Auch bei Spezialfonds, die f\u00fcr einzelne Kunden aufgelegt werden und daher vertraulich sind, k\u00f6nnten im Lebenslauf Angaben zur Performance gemacht werden, ohne die Diskretion zu verletzen. \u201eBei Sales-Positionen im Asset Management ist es ohnehin \u00fcblich Brutto- und Nettozufl\u00fcsse auf einer Extraliste nachzuweisen\u201c, erl\u00e4utert Rehwald.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch Behrens betont, wie wichtig eine detaillierte Auflistung der Performance bzw. der Vertriebsleistungen f\u00fcr einen Asset Management-Lebenslauf ist. Bei Sales-Leuten komme es auf die Kontakte an. Es werde allerdings immer noch gerne ein wenig geschummelt. \u201eGerade bei Sales-Lebensl\u00e4ufen m\u00fcssen Sie als Personalberater schon etwas genauer hinschauen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>4. \u2026 weist eine gute Ausbildung auf<\/mark><br>Keine Frage, eine gute Ausbildung ziert jeden Lebenslauf ungemein. \u201eEine Top-Uni, gute Noten und eine gute berufliche Ausbildung beispielsweise durch eine T\u00e4tigkeit als Junior-Portfoliomanager bzw. Sales, einige Jahre in einer Strategieabteilung oder andere gute Junior-Positionen zeichnen einen guten Lebenslauf aus\u201c, betont Behrens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>5. \u2026 enth\u00e4lt Zusatzqualifikationen wie den CFA<\/mark><br>\u201eEin Abschluss als CFA ist uns sehr wichtig, da hier international anerkannte und vergleichbare Standards hinterlegt sind\u201c, hei\u00dft es von Union Investment. \u201eEine von uns akzeptierte Alternative ist der deutsche DVFA (CIIA).\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eIm Portfoliomanagement wird ein CFA h\u00e4ufig gew\u00fcnscht und stellt auch ein gro\u00dfes Plus dar; es handelt sich aber nicht um einen Standard\u201c, erz\u00e4hlt Behrens. Auch im Sales w\u00fcrden die Arbeitgeber mittlerweile auf eine gute Ausbildung Wert legen. \u201eDie Zeit der Blender ist vorbei. Die Kunden verlangen heute, dass die Sales-Mitarbeiter sich in den Produkten deutlich besser auskennen als das fr\u00fcher der Fall gewesen ist.\u201c Oftmals k\u00f6nne schon das Bestehen des ersten oder zweiten der insgesamt drei CFA-Level bei einer Bewerbung weiterhelfen. Generell gelte es jeden bestandenen CFA-Level und \u00e4hnliche Fortbildungen in den Lebenslauf aufzunehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>6. \u2026 zeigt keine L\u00fccken<\/mark><br>L\u00fccken in Lebensl\u00e4ufen wirken auf Recruiter verd\u00e4chtig. Viele scannen daher die Werdeg\u00e4nge nach etwaigen Unstimmigkeiten. Auch der bekannte Trick, bei den Stationen nur Jahreszahlen anzugeben, um so kleinere L\u00fccken zu verstecken, funktioniert nicht immer. Die Personaler von Union Investment warnen schon einmal vorsorglich: \u201eLebensl\u00e4ufe, in denen zeitliche L\u00fccken bestehen oder bei denen die Zeitr\u00e4ume nur mit Jahreszahlen angegeben sind, helfen uns nicht weiter und werden oft aussortiert.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Asset Management geh\u00f6rt zu den wenigen Sektoren der Finanzdienstleistungen, die mit offenen Stellen gesegnet sind. \u201eEs bewegt sich momentan recht viel\u201c, beobachtet Personalberater Manuel Rehwald von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6774,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,44],"tags":[],"class_list":["post-6773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines","category-asset-management"],"_links":{"self":[{"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/posts\/6773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/comments?post=6773"}],"version-history":[{"count":1,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/posts\/6773\/revisions"}],"predecessor-version":[{"id":6776,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/posts\/6773\/revisions\/6776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/media\/6774"}],"wp:attachment":[{"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/media?parent=6773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/categories?post=6773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rehwald-associates.co.uk\/de\/wp-json\/wp\/v2\/tags?post=6773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}